{"id":3379,"date":"2021-02-07T19:30:00","date_gmt":"2021-02-07T18:30:00","guid":{"rendered":"https:\/\/ld-nrw.de\/?p=3379"},"modified":"2026-06-10T19:31:58","modified_gmt":"2026-06-10T17:31:58","slug":"sicherheitsgefuehl-auf-dem-weg-in-den-aachener-sueden","status":"publish","type":"post","link":"https:\/\/ld-nrw.de\/en\/aktuelles\/sicherheitsgefuehl-auf-dem-weg-in-den-aachener-sueden\/","title":{"rendered":"Sicherheitsgef\u00fchl auf dem Weg in den Aachener S\u00fcden"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Die Liberalen Demokraten Aachen wollen mit dem Fu\u00df- und Radweg zwischen Kamper Stra\u00dfe und Burtscheider Stra\u00dfe eine wichtige Wegeverbindung im Aachener S\u00fcden aufwerten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Derzeit ist der Weg in bedauernswertem Zustand. Die wenigen Lampen, die es gibt, sind derart mit Graffiti \u00fcbermalt, dass sie kaum noch Licht abgeben. B\u00e4nke sind schmutzig und oft mit Sperrm\u00fcll \u00fcbers\u00e4t. Gerade abends und nachts leidet unter den durch B\u00e4ume verdeckten Biegungen des Weges, der schlechten Beleuchtung und den fehlenden Ausweichm\u00f6glichkeiten das Sicherheitsgef\u00fchl.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das ist eine vertane Chance f\u00fcr die Verbindung zwischen Bahnhof und S\u00fcdviertel. Es handelt sich um eine nicht nur praktische, sondern auch sch\u00f6ne Abk\u00fcrzung mit interessanten Einblicken in den Bahnverkehr und Ausblicken \u00fcber das Gleisvorfeld des Bahnhofs. Deshalb wollen wir den Weg wie folgt aufwerten:<\/p>\n\n\n\n<ul id=\"block-d9ead3f3-d139-4f6d-b0ed-bd49b5f41dfb\" class=\"wp-block-list\">\n<li>Gute Beleuchtung rund um die Uhr<\/li>\n\n\n\n<li>Zur\u00fcckschneiden der Randbepflanzung f\u00fcr Sicherheitsgef\u00fchl und Ausblick<\/li>\n\n\n\n<li>Sitzgelegenheiten am Steilhang anhand von Sitzstufen ober- und unterhalb des Weges, die Aufenthalts- und Ausweichr\u00e4ume bieten<\/li>\n\n\n\n<li>Schaffung eines Lehrpfads zur Bahngeschichte direkt neben dem aktiven Bahnverkehr entlang des Weges<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Die Liberalen Demokraten Aachen wollen mit dem Fu\u00df- und Radweg zwischen Kamper Stra\u00dfe und Burtscheider Stra\u00dfe eine wichtige Wegeverbindung im Aachener S\u00fcden aufwerten. Derzeit ist der Weg in bedauernswertem Zustand. Die wenigen Lampen, die es gibt, sind derart mit Graffiti \u00fcbermalt, dass sie kaum noch Licht abgeben. B\u00e4nke sind schmutzig und oft mit Sperrm\u00fcll \u00fcbers\u00e4t. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3380,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[34,33],"tags":[19,72,47,73],"class_list":["post-3379","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aachen","category-lokales","tag-aachen","tag-fussweg","tag-kommunalpolitik","tag-staedtebau"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sicherheitsgef\u00fchl auf dem Weg in den Aachener S\u00fcden - Liberale Demokraten NRW<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ld-nrw.de\/en\/aktuelles\/sicherheitsgefuehl-auf-dem-weg-in-den-aachener-sueden\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sicherheitsgef\u00fchl auf dem Weg in den Aachener S\u00fcden - Liberale Demokraten NRW\" \/>\n<meta property=\"og:description\" content=\"Die Liberalen Demokraten Aachen wollen mit dem Fu\u00df- und Radweg zwischen Kamper Stra\u00dfe und Burtscheider Stra\u00dfe eine wichtige Wegeverbindung im Aachener S\u00fcden aufwerten. Derzeit ist der Weg in bedauernswertem Zustand. Die wenigen Lampen, die es gibt, sind derart mit Graffiti \u00fcbermalt, dass sie kaum noch Licht abgeben. B\u00e4nke sind schmutzig und oft mit Sperrm\u00fcll \u00fcbers\u00e4t. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ld-nrw.de\/en\/aktuelles\/sicherheitsgefuehl-auf-dem-weg-in-den-aachener-sueden\/\" \/>\n<meta property=\"og:site_name\" content=\"Liberale Demokraten NRW\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ldnrw\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/vossiek.paul\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-07T18:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-10T17:31:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ld-nrw.de\/wp-content\/uploads\/2026\/06\/aachen_kamper_str-400x250-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Paul Vossiek\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/paulvossiek\" \/>\n<meta name=\"twitter:site\" content=\"@ld_nrw\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Paul Vossiek\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/sicherheitsgefuehl-auf-dem-weg-in-den-aachener-sueden\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/sicherheitsgefuehl-auf-dem-weg-in-den-aachener-sueden\\\/\"},\"author\":{\"name\":\"Paul Vossiek\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#\\\/schema\\\/person\\\/2425cac6c653ccad7b40a927e0bb88ab\"},\"headline\":\"Sicherheitsgef\u00fchl auf dem Weg in den Aachener S\u00fcden\",\"datePublished\":\"2021-02-07T18:30:00+00:00\",\"dateModified\":\"2026-06-10T17:31:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/sicherheitsgefuehl-auf-dem-weg-in-den-aachener-sueden\\\/\"},\"wordCount\":192,\"publisher\":{\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/sicherheitsgefuehl-auf-dem-weg-in-den-aachener-sueden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ld-nrw.de\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/aachen_kamper_str-400x250-1.jpg\",\"keywords\":[\"Aachen\",\"Fu\u00dfweg\",\"Kommunalpolitik\",\"St\u00e4dtebau\"],\"articleSection\":[\"Aachen\",\"Lokales\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/sicherheitsgefuehl-auf-dem-weg-in-den-aachener-sueden\\\/\",\"url\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/sicherheitsgefuehl-auf-dem-weg-in-den-aachener-sueden\\\/\",\"name\":\"Sicherheitsgef\u00fchl auf dem Weg in den Aachener S\u00fcden - Liberale Demokraten NRW\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/sicherheitsgefuehl-auf-dem-weg-in-den-aachener-sueden\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/sicherheitsgefuehl-auf-dem-weg-in-den-aachener-sueden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ld-nrw.de\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/aachen_kamper_str-400x250-1.jpg\",\"datePublished\":\"2021-02-07T18:30:00+00:00\",\"dateModified\":\"2026-06-10T17:31:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/sicherheitsgefuehl-auf-dem-weg-in-den-aachener-sueden\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/sicherheitsgefuehl-auf-dem-weg-in-den-aachener-sueden\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/sicherheitsgefuehl-auf-dem-weg-in-den-aachener-sueden\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ld-nrw.de\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/aachen_kamper_str-400x250-1.jpg\",\"contentUrl\":\"https:\\\/\\\/ld-nrw.de\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/aachen_kamper_str-400x250-1.jpg\",\"width\":400,\"height\":250},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/sicherheitsgefuehl-auf-dem-weg-in-den-aachener-sueden\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/ld-nrw.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sicherheitsgef\u00fchl auf dem Weg in den Aachener S\u00fcden\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#website\",\"url\":\"https:\\\/\\\/ld-nrw.de\\\/\",\"name\":\"Liberale Demokraten NRW\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ld-nrw.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#organization\",\"name\":\"Liberale Demokraten NRW\",\"url\":\"https:\\\/\\\/ld-nrw.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ld-nrw.de\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/ld_nrw.svg\",\"contentUrl\":\"https:\\\/\\\/ld-nrw.de\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/ld_nrw.svg\",\"width\":1595,\"height\":776,\"caption\":\"Liberale Demokraten NRW\"},\"image\":{\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ldnrw\",\"https:\\\/\\\/x.com\\\/ld_nrw\",\"https:\\\/\\\/www.instagram.com\\\/ld_nrw\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#\\\/schema\\\/person\\\/2425cac6c653ccad7b40a927e0bb88ab\",\"name\":\"Paul Vossiek\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/bpt2025_pb-96x96.jpg\",\"url\":\"https:\\\/\\\/ld-nrw.de\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/bpt2025_pb-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/ld-nrw.de\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/bpt2025_pb-96x96.jpg\",\"caption\":\"Paul Vossiek\"},\"description\":\"Paul Vossiek engagiert sich seit 2019 in verschiedenen Rollen bei den Liberalen Demokraten. Von 2023 bis 2026 hatte er den Bundesvorsitz der sozialliberalen Partei inne. Zur Landtagswahl 2027 in Nordrhein-Westfalen kandidiert er als Spitzenkandidat und f\u00fcr den Wahlkreis Aachen I. Er arbeitet als Ingenieur in der Elektroindustrie. Zuvor schloss eh ein Bachelorstudium in Elektrotechnik, Informationstechnik und Technischer Informatik und ein Masterstudium in der Fachrichtung Computer Engineering an der RWTH Aachen erfolgreich ab. Paul Vossiek ist Mitglied und Leiter des Fachforums \u201eInnovationen, KI und Digitalisierung\u201c beim Verein \u00d6kologische Marktwirtschaft (\u00d6kMa). Weitere Mitgliedschaften unterh\u00e4lt er bei Transparency International und dem Verkehrsclub Deutschland. Politisch besch\u00e4ftigt er sich besonders in den Themen B\u00fcrgerrechte und Wirtschaft. Sein Herzensthema: Generationengerechtigkeit im Angesicht des demografischen Wandels und des Klimanotstands.\",\"sameAs\":[\"https:\\\/\\\/paulvossiek.de\",\"https:\\\/\\\/www.facebook.com\\\/vossiek.paul\",\"https:\\\/\\\/www.instagram.com\\\/paulvossiek\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/paulvossiek\"],\"url\":\"https:\\\/\\\/ld-nrw.de\\\/en\\\/aktuelles\\\/author\\\/paulvossiek\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sicherheitsgef\u00fchl auf dem Weg in den Aachener S\u00fcden - Liberale Demokraten NRW","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ld-nrw.de\/en\/aktuelles\/sicherheitsgefuehl-auf-dem-weg-in-den-aachener-sueden\/","og_locale":"en_GB","og_type":"article","og_title":"Sicherheitsgef\u00fchl auf dem Weg in den Aachener S\u00fcden - Liberale Demokraten NRW","og_description":"Die Liberalen Demokraten Aachen wollen mit dem Fu\u00df- und Radweg zwischen Kamper Stra\u00dfe und Burtscheider Stra\u00dfe eine wichtige Wegeverbindung im Aachener S\u00fcden aufwerten. Derzeit ist der Weg in bedauernswertem Zustand. Die wenigen Lampen, die es gibt, sind derart mit Graffiti \u00fcbermalt, dass sie kaum noch Licht abgeben. B\u00e4nke sind schmutzig und oft mit Sperrm\u00fcll \u00fcbers\u00e4t. [&hellip;]","og_url":"https:\/\/ld-nrw.de\/en\/aktuelles\/sicherheitsgefuehl-auf-dem-weg-in-den-aachener-sueden\/","og_site_name":"Liberale Demokraten NRW","article_publisher":"https:\/\/www.facebook.com\/ldnrw","article_author":"https:\/\/www.facebook.com\/vossiek.paul","article_published_time":"2021-02-07T18:30:00+00:00","article_modified_time":"2026-06-10T17:31:58+00:00","og_image":[{"width":400,"height":250,"url":"https:\/\/ld-nrw.de\/wp-content\/uploads\/2026\/06\/aachen_kamper_str-400x250-1.jpg","type":"image\/jpeg"}],"author":"Paul Vossiek","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/paulvossiek","twitter_site":"@ld_nrw","twitter_misc":{"Written by":"Paul Vossiek","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ld-nrw.de\/aktuelles\/sicherheitsgefuehl-auf-dem-weg-in-den-aachener-sueden\/#article","isPartOf":{"@id":"https:\/\/ld-nrw.de\/aktuelles\/sicherheitsgefuehl-auf-dem-weg-in-den-aachener-sueden\/"},"author":{"name":"Paul Vossiek","@id":"https:\/\/ld-nrw.de\/#\/schema\/person\/2425cac6c653ccad7b40a927e0bb88ab"},"headline":"Sicherheitsgef\u00fchl auf dem Weg in den Aachener S\u00fcden","datePublished":"2021-02-07T18:30:00+00:00","dateModified":"2026-06-10T17:31:58+00:00","mainEntityOfPage":{"@id":"https:\/\/ld-nrw.de\/aktuelles\/sicherheitsgefuehl-auf-dem-weg-in-den-aachener-sueden\/"},"wordCount":192,"publisher":{"@id":"https:\/\/ld-nrw.de\/#organization"},"image":{"@id":"https:\/\/ld-nrw.de\/aktuelles\/sicherheitsgefuehl-auf-dem-weg-in-den-aachener-sueden\/#primaryimage"},"thumbnailUrl":"https:\/\/ld-nrw.de\/wp-content\/uploads\/2026\/06\/aachen_kamper_str-400x250-1.jpg","keywords":["Aachen","Fu\u00dfweg","Kommunalpolitik","St\u00e4dtebau"],"articleSection":["Aachen","Lokales"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/ld-nrw.de\/aktuelles\/sicherheitsgefuehl-auf-dem-weg-in-den-aachener-sueden\/","url":"https:\/\/ld-nrw.de\/aktuelles\/sicherheitsgefuehl-auf-dem-weg-in-den-aachener-sueden\/","name":"Sicherheitsgef\u00fchl auf dem Weg in den Aachener S\u00fcden - Liberale Demokraten NRW","isPartOf":{"@id":"https:\/\/ld-nrw.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ld-nrw.de\/aktuelles\/sicherheitsgefuehl-auf-dem-weg-in-den-aachener-sueden\/#primaryimage"},"image":{"@id":"https:\/\/ld-nrw.de\/aktuelles\/sicherheitsgefuehl-auf-dem-weg-in-den-aachener-sueden\/#primaryimage"},"thumbnailUrl":"https:\/\/ld-nrw.de\/wp-content\/uploads\/2026\/06\/aachen_kamper_str-400x250-1.jpg","datePublished":"2021-02-07T18:30:00+00:00","dateModified":"2026-06-10T17:31:58+00:00","breadcrumb":{"@id":"https:\/\/ld-nrw.de\/aktuelles\/sicherheitsgefuehl-auf-dem-weg-in-den-aachener-sueden\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ld-nrw.de\/aktuelles\/sicherheitsgefuehl-auf-dem-weg-in-den-aachener-sueden\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/ld-nrw.de\/aktuelles\/sicherheitsgefuehl-auf-dem-weg-in-den-aachener-sueden\/#primaryimage","url":"https:\/\/ld-nrw.de\/wp-content\/uploads\/2026\/06\/aachen_kamper_str-400x250-1.jpg","contentUrl":"https:\/\/ld-nrw.de\/wp-content\/uploads\/2026\/06\/aachen_kamper_str-400x250-1.jpg","width":400,"height":250},{"@type":"BreadcrumbList","@id":"https:\/\/ld-nrw.de\/aktuelles\/sicherheitsgefuehl-auf-dem-weg-in-den-aachener-sueden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/ld-nrw.de\/"},{"@type":"ListItem","position":2,"name":"Sicherheitsgef\u00fchl auf dem Weg in den Aachener S\u00fcden"}]},{"@type":"WebSite","@id":"https:\/\/ld-nrw.de\/#website","url":"https:\/\/ld-nrw.de\/","name":"Liberale Demokraten NRW","description":"","publisher":{"@id":"https:\/\/ld-nrw.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ld-nrw.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/ld-nrw.de\/#organization","name":"Liberale Demokraten NRW","url":"https:\/\/ld-nrw.de\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/ld-nrw.de\/#\/schema\/logo\/image\/","url":"https:\/\/ld-nrw.de\/wp-content\/uploads\/2023\/07\/ld_nrw.svg","contentUrl":"https:\/\/ld-nrw.de\/wp-content\/uploads\/2023\/07\/ld_nrw.svg","width":1595,"height":776,"caption":"Liberale Demokraten NRW"},"image":{"@id":"https:\/\/ld-nrw.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ldnrw","https:\/\/x.com\/ld_nrw","https:\/\/www.instagram.com\/ld_nrw\/"]},{"@type":"Person","@id":"https:\/\/ld-nrw.de\/#\/schema\/person\/2425cac6c653ccad7b40a927e0bb88ab","name":"Paul Vossiek","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/ld-nrw.de\/wp-content\/uploads\/2023\/07\/bpt2025_pb-96x96.jpg","url":"https:\/\/ld-nrw.de\/wp-content\/uploads\/2023\/07\/bpt2025_pb-96x96.jpg","contentUrl":"https:\/\/ld-nrw.de\/wp-content\/uploads\/2023\/07\/bpt2025_pb-96x96.jpg","caption":"Paul Vossiek"},"description":"Paul Vossiek engagiert sich seit 2019 in verschiedenen Rollen bei den Liberalen Demokraten. Von 2023 bis 2026 hatte er den Bundesvorsitz der sozialliberalen Partei inne. Zur Landtagswahl 2027 in Nordrhein-Westfalen kandidiert er als Spitzenkandidat und f\u00fcr den Wahlkreis Aachen I. Er arbeitet als Ingenieur in der Elektroindustrie. Zuvor schloss eh ein Bachelorstudium in Elektrotechnik, Informationstechnik und Technischer Informatik und ein Masterstudium in der Fachrichtung Computer Engineering an der RWTH Aachen erfolgreich ab. Paul Vossiek ist Mitglied und Leiter des Fachforums \u201eInnovationen, KI und Digitalisierung\u201c beim Verein \u00d6kologische Marktwirtschaft (\u00d6kMa). Weitere Mitgliedschaften unterh\u00e4lt er bei Transparency International und dem Verkehrsclub Deutschland. Politisch besch\u00e4ftigt er sich besonders in den Themen B\u00fcrgerrechte und Wirtschaft. Sein Herzensthema: Generationengerechtigkeit im Angesicht des demografischen Wandels und des Klimanotstands.","sameAs":["https:\/\/paulvossiek.de","https:\/\/www.facebook.com\/vossiek.paul","https:\/\/www.instagram.com\/paulvossiek\/","https:\/\/x.com\/https:\/\/twitter.com\/paulvossiek"],"url":"https:\/\/ld-nrw.de\/en\/aktuelles\/author\/paulvossiek\/"}]}},"_links":{"self":[{"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/posts\/3379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/comments?post=3379"}],"version-history":[{"count":1,"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/posts\/3379\/revisions"}],"predecessor-version":[{"id":3381,"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/posts\/3379\/revisions\/3381"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/media\/3380"}],"wp:attachment":[{"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/media?parent=3379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/categories?post=3379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/tags?post=3379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}