{"id":2798,"date":"2024-10-17T21:30:32","date_gmt":"2024-10-17T19:30:32","guid":{"rendered":"https:\/\/ld-nrw.de\/?p=2798"},"modified":"2024-10-17T21:30:57","modified_gmt":"2024-10-17T19:30:57","slug":"finanzkriminalitaet-effektiv-verfolgen-statt-sich-ihr-anzubiedern","status":"publish","type":"post","link":"https:\/\/ld-nrw.de\/en\/aktuelles\/finanzkriminalitaet-effektiv-verfolgen-statt-sich-ihr-anzubiedern\/","title":{"rendered":"Finanzkriminalit\u00e4t effektiv verfolgen, statt sich ihr anzubiedern"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Es ist nicht allzu lange her, dass die nordrhein-westf\u00e4lische Chefermittlerin des h\u00f6chst relevanten \u201eCum-Ex\u201c-Skandals, Anne Brorhilker, ihren Posten ger\u00e4umt hat. Auch wenn die unmittelbaren Umst\u00e4nde, die sie zu diesem Schritt gezwungen haben, nicht \u00f6ffentlich sind, so hat die ehemalige Finanzstaatsanw\u00e4ltin und heutige Mitarbeiterin des Finanzlobbyismus-kritischen Vereins \u201eB\u00fcrgerbewegung Finanzwende\u201c kein gutes Haar an der deutschen Verfolgung von Finanzstraftaten gelassen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dass sie ihre Arbeit in der Staatsanwaltschaft K\u00f6ln nicht ohne G\u00e4ngeleien aus\u00fcben konnte, ist sp\u00e4testens seit den \u00f6ffentlichen Nachtritten ihres ehemaligen Vorgesetzten im Zust\u00e4ndigkeitsbereich des&nbsp; NRW-Justizministers Benjamin Limbach (B\u00fcndnis 90\/ Die Gr\u00fcnen) wenigstens zu vermuten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nicht nur wir Liberale Demokraten, sondern auch die Landtagsfraktion der FDP und politische Mandatstr\u00e4ger und Funktion\u00e4re der SPD, kommen zu der Einsch\u00e4tzung, dass Frau Brorhilker eine f\u00e4hige Staatsanw\u00e4ltin war und sich die nordrhein-westf\u00e4lische Landesregierung str\u00e4ubt, den gr\u00f6\u00dften Finanzskandal der Bundesrepublik effektiv aufzuarbeiten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Somit sprechen wir Frau Brorhilker in ihrer neuen T\u00e4tigkeit unsere volle Unterst\u00fctzung aus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finanzkriminalit\u00e4t muss effektiv bek\u00e4mpft werden. Insbesondere, wenn sie kaum fassbare Ausma\u00dfe wie der Cum-Ex-Skandal, annimmt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir fordern die Landesregierung NRW und speziell den Landesjustizminister Limbach auf, die Verfolgung der Cum-Ex-T\u00e4ter mit allen Mitteln des Rechtsstaats zu intensivieren. Das bedeutet auch, den Ermittlern keine weiteren Steine in den Weg zu legen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Weiterhin fordern wir von der Landesregierung absolute Transparenz bez\u00fcglich der Aufarbeitung des Skandals. Schlie\u00dflich geht es um Milliarden-Sch\u00e4den im bundesdeutschen Haushalt. Milliarden, die wir heutzutage gut gebrauchen k\u00f6nnten.<\/p>","protected":false},"excerpt":{"rendered":"<p>Es ist nicht allzu lange her, dass die nordrhein-westf\u00e4lische Chefermittlerin des h\u00f6chst relevanten \u201eCum-Ex\u201c-Skandals, Anne Brorhilker, ihren Posten ger\u00e4umt hat. Auch wenn die unmittelbaren Umst\u00e4nde, die sie zu diesem Schritt gezwungen haben, nicht \u00f6ffentlich sind, so hat die ehemalige Finanzstaatsanw\u00e4ltin und heutige Mitarbeiterin des Finanzlobbyismus-kritischen Vereins \u201eB\u00fcrgerbewegung Finanzwende\u201c kein gutes Haar an der deutschen Verfolgung [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":2799,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-2798","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kommentare"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Finanzkriminalit\u00e4t effektiv verfolgen, statt sich ihr anzubiedern - Liberale Demokraten NRW<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ld-nrw.de\/en\/aktuelles\/finanzkriminalitaet-effektiv-verfolgen-statt-sich-ihr-anzubiedern\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Finanzkriminalit\u00e4t effektiv verfolgen, statt sich ihr anzubiedern - Liberale Demokraten NRW\" \/>\n<meta property=\"og:description\" content=\"Es ist nicht allzu lange her, dass die nordrhein-westf\u00e4lische Chefermittlerin des h\u00f6chst relevanten \u201eCum-Ex\u201c-Skandals, Anne Brorhilker, ihren Posten ger\u00e4umt hat. Auch wenn die unmittelbaren Umst\u00e4nde, die sie zu diesem Schritt gezwungen haben, nicht \u00f6ffentlich sind, so hat die ehemalige Finanzstaatsanw\u00e4ltin und heutige Mitarbeiterin des Finanzlobbyismus-kritischen Vereins \u201eB\u00fcrgerbewegung Finanzwende\u201c kein gutes Haar an der deutschen Verfolgung [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ld-nrw.de\/en\/aktuelles\/finanzkriminalitaet-effektiv-verfolgen-statt-sich-ihr-anzubiedern\/\" \/>\n<meta property=\"og:site_name\" content=\"Liberale Demokraten NRW\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ldnrw\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-17T19:30:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-17T19:30:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ld-nrw.de\/wp-content\/uploads\/2024\/10\/michael-held-abYqTiV2pwk-unsplash-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Julian Oster\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ld_nrw\" \/>\n<meta name=\"twitter:site\" content=\"@ld_nrw\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julian Oster\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/finanzkriminalitaet-effektiv-verfolgen-statt-sich-ihr-anzubiedern\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/finanzkriminalitaet-effektiv-verfolgen-statt-sich-ihr-anzubiedern\\\/\"},\"author\":{\"name\":\"Julian Oster\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#\\\/schema\\\/person\\\/eaf94b1109eee4b9f6249b9def75b34d\"},\"headline\":\"Finanzkriminalit\u00e4t effektiv verfolgen, statt sich ihr anzubiedern\",\"datePublished\":\"2024-10-17T19:30:32+00:00\",\"dateModified\":\"2024-10-17T19:30:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/finanzkriminalitaet-effektiv-verfolgen-statt-sich-ihr-anzubiedern\\\/\"},\"wordCount\":266,\"publisher\":{\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/finanzkriminalitaet-effektiv-verfolgen-statt-sich-ihr-anzubiedern\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ld-nrw.de\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/michael-held-abYqTiV2pwk-unsplash-scaled.jpg\",\"articleSection\":[\"Kommentar\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/finanzkriminalitaet-effektiv-verfolgen-statt-sich-ihr-anzubiedern\\\/\",\"url\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/finanzkriminalitaet-effektiv-verfolgen-statt-sich-ihr-anzubiedern\\\/\",\"name\":\"Finanzkriminalit\u00e4t effektiv verfolgen, statt sich ihr anzubiedern - Liberale Demokraten NRW\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/finanzkriminalitaet-effektiv-verfolgen-statt-sich-ihr-anzubiedern\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/finanzkriminalitaet-effektiv-verfolgen-statt-sich-ihr-anzubiedern\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ld-nrw.de\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/michael-held-abYqTiV2pwk-unsplash-scaled.jpg\",\"datePublished\":\"2024-10-17T19:30:32+00:00\",\"dateModified\":\"2024-10-17T19:30:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/finanzkriminalitaet-effektiv-verfolgen-statt-sich-ihr-anzubiedern\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/finanzkriminalitaet-effektiv-verfolgen-statt-sich-ihr-anzubiedern\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/finanzkriminalitaet-effektiv-verfolgen-statt-sich-ihr-anzubiedern\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ld-nrw.de\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/michael-held-abYqTiV2pwk-unsplash-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/ld-nrw.de\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/michael-held-abYqTiV2pwk-unsplash-scaled.jpg\",\"width\":2560,\"height\":2048},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/finanzkriminalitaet-effektiv-verfolgen-statt-sich-ihr-anzubiedern\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/ld-nrw.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Finanzkriminalit\u00e4t effektiv verfolgen, statt sich ihr anzubiedern\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#website\",\"url\":\"https:\\\/\\\/ld-nrw.de\\\/\",\"name\":\"Liberale Demokraten NRW\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ld-nrw.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#organization\",\"name\":\"Liberale Demokraten NRW\",\"url\":\"https:\\\/\\\/ld-nrw.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ld-nrw.de\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/ld_nrw.svg\",\"contentUrl\":\"https:\\\/\\\/ld-nrw.de\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/ld_nrw.svg\",\"width\":1595,\"height\":776,\"caption\":\"Liberale Demokraten NRW\"},\"image\":{\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ldnrw\",\"https:\\\/\\\/x.com\\\/ld_nrw\",\"https:\\\/\\\/www.instagram.com\\\/ld_nrw\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#\\\/schema\\\/person\\\/eaf94b1109eee4b9f6249b9def75b34d\",\"name\":\"Julian Oster\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/julian_oster-96x96.jpg\",\"url\":\"https:\\\/\\\/ld-nrw.de\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/julian_oster-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/ld-nrw.de\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/julian_oster-96x96.jpg\",\"caption\":\"Julian Oster\"},\"description\":\"Julian ist Student der Rechtswissenschaften. Mit 18 Jahren ist er in die Liberalen Demokraten eingetreten. F\u00fcr ihn geht Freiheit nicht ohne Chancengerechtigkeit.\",\"url\":\"https:\\\/\\\/ld-nrw.de\\\/en\\\/aktuelles\\\/author\\\/julianoster\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Finanzkriminalit\u00e4t effektiv verfolgen, statt sich ihr anzubiedern - Liberale Demokraten NRW","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ld-nrw.de\/en\/aktuelles\/finanzkriminalitaet-effektiv-verfolgen-statt-sich-ihr-anzubiedern\/","og_locale":"en_GB","og_type":"article","og_title":"Finanzkriminalit\u00e4t effektiv verfolgen, statt sich ihr anzubiedern - Liberale Demokraten NRW","og_description":"Es ist nicht allzu lange her, dass die nordrhein-westf\u00e4lische Chefermittlerin des h\u00f6chst relevanten \u201eCum-Ex\u201c-Skandals, Anne Brorhilker, ihren Posten ger\u00e4umt hat. Auch wenn die unmittelbaren Umst\u00e4nde, die sie zu diesem Schritt gezwungen haben, nicht \u00f6ffentlich sind, so hat die ehemalige Finanzstaatsanw\u00e4ltin und heutige Mitarbeiterin des Finanzlobbyismus-kritischen Vereins \u201eB\u00fcrgerbewegung Finanzwende\u201c kein gutes Haar an der deutschen Verfolgung [&hellip;]","og_url":"https:\/\/ld-nrw.de\/en\/aktuelles\/finanzkriminalitaet-effektiv-verfolgen-statt-sich-ihr-anzubiedern\/","og_site_name":"Liberale Demokraten NRW","article_publisher":"https:\/\/www.facebook.com\/ldnrw","article_published_time":"2024-10-17T19:30:32+00:00","article_modified_time":"2024-10-17T19:30:57+00:00","og_image":[{"width":2560,"height":2048,"url":"https:\/\/ld-nrw.de\/wp-content\/uploads\/2024\/10\/michael-held-abYqTiV2pwk-unsplash-scaled.jpg","type":"image\/jpeg"}],"author":"Julian Oster","twitter_card":"summary_large_image","twitter_creator":"@ld_nrw","twitter_site":"@ld_nrw","twitter_misc":{"Written by":"Julian Oster","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ld-nrw.de\/aktuelles\/finanzkriminalitaet-effektiv-verfolgen-statt-sich-ihr-anzubiedern\/#article","isPartOf":{"@id":"https:\/\/ld-nrw.de\/aktuelles\/finanzkriminalitaet-effektiv-verfolgen-statt-sich-ihr-anzubiedern\/"},"author":{"name":"Julian Oster","@id":"https:\/\/ld-nrw.de\/#\/schema\/person\/eaf94b1109eee4b9f6249b9def75b34d"},"headline":"Finanzkriminalit\u00e4t effektiv verfolgen, statt sich ihr anzubiedern","datePublished":"2024-10-17T19:30:32+00:00","dateModified":"2024-10-17T19:30:57+00:00","mainEntityOfPage":{"@id":"https:\/\/ld-nrw.de\/aktuelles\/finanzkriminalitaet-effektiv-verfolgen-statt-sich-ihr-anzubiedern\/"},"wordCount":266,"publisher":{"@id":"https:\/\/ld-nrw.de\/#organization"},"image":{"@id":"https:\/\/ld-nrw.de\/aktuelles\/finanzkriminalitaet-effektiv-verfolgen-statt-sich-ihr-anzubiedern\/#primaryimage"},"thumbnailUrl":"https:\/\/ld-nrw.de\/wp-content\/uploads\/2024\/10\/michael-held-abYqTiV2pwk-unsplash-scaled.jpg","articleSection":["Kommentar"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/ld-nrw.de\/aktuelles\/finanzkriminalitaet-effektiv-verfolgen-statt-sich-ihr-anzubiedern\/","url":"https:\/\/ld-nrw.de\/aktuelles\/finanzkriminalitaet-effektiv-verfolgen-statt-sich-ihr-anzubiedern\/","name":"Finanzkriminalit\u00e4t effektiv verfolgen, statt sich ihr anzubiedern - Liberale Demokraten NRW","isPartOf":{"@id":"https:\/\/ld-nrw.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ld-nrw.de\/aktuelles\/finanzkriminalitaet-effektiv-verfolgen-statt-sich-ihr-anzubiedern\/#primaryimage"},"image":{"@id":"https:\/\/ld-nrw.de\/aktuelles\/finanzkriminalitaet-effektiv-verfolgen-statt-sich-ihr-anzubiedern\/#primaryimage"},"thumbnailUrl":"https:\/\/ld-nrw.de\/wp-content\/uploads\/2024\/10\/michael-held-abYqTiV2pwk-unsplash-scaled.jpg","datePublished":"2024-10-17T19:30:32+00:00","dateModified":"2024-10-17T19:30:57+00:00","breadcrumb":{"@id":"https:\/\/ld-nrw.de\/aktuelles\/finanzkriminalitaet-effektiv-verfolgen-statt-sich-ihr-anzubiedern\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ld-nrw.de\/aktuelles\/finanzkriminalitaet-effektiv-verfolgen-statt-sich-ihr-anzubiedern\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/ld-nrw.de\/aktuelles\/finanzkriminalitaet-effektiv-verfolgen-statt-sich-ihr-anzubiedern\/#primaryimage","url":"https:\/\/ld-nrw.de\/wp-content\/uploads\/2024\/10\/michael-held-abYqTiV2pwk-unsplash-scaled.jpg","contentUrl":"https:\/\/ld-nrw.de\/wp-content\/uploads\/2024\/10\/michael-held-abYqTiV2pwk-unsplash-scaled.jpg","width":2560,"height":2048},{"@type":"BreadcrumbList","@id":"https:\/\/ld-nrw.de\/aktuelles\/finanzkriminalitaet-effektiv-verfolgen-statt-sich-ihr-anzubiedern\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/ld-nrw.de\/"},{"@type":"ListItem","position":2,"name":"Finanzkriminalit\u00e4t effektiv verfolgen, statt sich ihr anzubiedern"}]},{"@type":"WebSite","@id":"https:\/\/ld-nrw.de\/#website","url":"https:\/\/ld-nrw.de\/","name":"Liberale Demokraten NRW","description":"","publisher":{"@id":"https:\/\/ld-nrw.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ld-nrw.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/ld-nrw.de\/#organization","name":"Liberale Demokraten NRW","url":"https:\/\/ld-nrw.de\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/ld-nrw.de\/#\/schema\/logo\/image\/","url":"https:\/\/ld-nrw.de\/wp-content\/uploads\/2023\/07\/ld_nrw.svg","contentUrl":"https:\/\/ld-nrw.de\/wp-content\/uploads\/2023\/07\/ld_nrw.svg","width":1595,"height":776,"caption":"Liberale Demokraten NRW"},"image":{"@id":"https:\/\/ld-nrw.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ldnrw","https:\/\/x.com\/ld_nrw","https:\/\/www.instagram.com\/ld_nrw\/"]},{"@type":"Person","@id":"https:\/\/ld-nrw.de\/#\/schema\/person\/eaf94b1109eee4b9f6249b9def75b34d","name":"Julian Oster","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/ld-nrw.de\/wp-content\/uploads\/2024\/09\/julian_oster-96x96.jpg","url":"https:\/\/ld-nrw.de\/wp-content\/uploads\/2024\/09\/julian_oster-96x96.jpg","contentUrl":"https:\/\/ld-nrw.de\/wp-content\/uploads\/2024\/09\/julian_oster-96x96.jpg","caption":"Julian Oster"},"description":"Julian is a law student. He joined the Liberale Demokraten at the age of 18. For him, freedom is not possible without equal opportunities.","url":"https:\/\/ld-nrw.de\/en\/aktuelles\/author\/julianoster\/"}]}},"_links":{"self":[{"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/posts\/2798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/comments?post=2798"}],"version-history":[{"count":1,"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/posts\/2798\/revisions"}],"predecessor-version":[{"id":2800,"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/posts\/2798\/revisions\/2800"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/media\/2799"}],"wp:attachment":[{"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/media?parent=2798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/categories?post=2798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/tags?post=2798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}