{"id":1391,"date":"2020-07-02T18:00:00","date_gmt":"2020-07-02T16:00:00","guid":{"rendered":"https:\/\/ld-nrw.de\/?p=1391"},"modified":"2023-11-28T12:05:56","modified_gmt":"2023-11-28T11:05:56","slug":"uferboeschungen-am-tagebau-hambach","status":"publish","type":"post","link":"https:\/\/ld-nrw.de\/en\/aktuelles\/uferboeschungen-am-tagebau-hambach\/","title":{"rendered":"Uferb\u00f6schungen am Tagebau Hambach"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Die Liberalen Demokraten NRW unterst\u00fctzen die Forderungen der am Tagebau Hambach sans\u00e4ssigen Landwirte, Grundbesitzer und Gemeinden keine Acker- und Landfl\u00e4chen zur Herstellung abgeflachter Uferb\u00f6schungen abzubaggern und zu zerst\u00f6ren. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auch die Fl\u00e4che des inzwischen fast v\u00f6llig zerst\u00f6rten Ortes Alt-Manheim kann f\u00fcr eine neue Ortsansiedlung genutzt werden, da alle Infratsrukturen bereits liegen. Hier k\u00f6nnte beispielsweise eine Niedrigenergiesiedlung entstehen. Wir unterst\u00fctzen die Forderung zur Randabflachung die noch nicht rekultivierten Teile der Sophienh\u00f6he und wenn n\u00f6tig weitere Bereiche dieser Abraumhalde heranzuziehen und somit die bestehenden Landfl\u00e4chen am Grubenrand zu erhalten. Dies sollte etappenweise m\u00f6glich sein, ohne die Sophienh\u00f6he zu destabilisieren. Hierf\u00fcr sind entsprechende Pl\u00e4ne zu erarbeiten. Die Ausreden der RWE, dass die Kippe 40 Jahre alt ist, die Artenvielfalt sch\u00fctzenswert und dass es nicht m\u00f6glich sein diese aufgesch\u00fcttete Kippe wieder in Teilen abzutragen, weisen wir als haltlos ab. Dies ist lediglich eine Augenwischerei um die nicht ortskundige \u00d6ffentlichkeit zu beschwichtigen. Wer mit steilen Kanten einen mehrere hundert Meter tiefen Tagebau stabil betreiben kann, der kann auch eine Abraumhalde wieder abtragen, ohne diese zu Destabilisieren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Kippe wird auch aktuell durch Aufsch\u00fcttung abgebaggerten Abraums erweitert, statt diesen bereits seit Monaten zur Abflachung der Tagebaukanten heran zu ziehen. Auch sind ein Gro\u00dfteil der Sophienh\u00f6he weitaus j\u00fcnger als 30 Jahre und noch nicht rekultiviert bzw nur im Ansatz. Die Sophienh\u00f6he war bereits im Zustand vor 20-30 Jahren ohne weitere Ansch\u00fcttungen stabil und sollte daher auf dieses Niveau zur\u00fcckgebaut werden k\u00f6nnen. Das Thema Artenschutz hier von RWE auf den Plan zu bringen ist wohl an Dreistigkeit nicht zu \u00fcberbieten, immerhin war es RWE, die einen Jahrtausende alten Wald (B\u00fcrgewald, &#8222;Hambi&#8220;) bereits zum Gro\u00dfteil abgeholtz und zerst\u00f6rt haben und die ihn auch gerne v\u00f6llig ausgel\u00f6scht h\u00e4tten. Hier war der RWE jedweder Artenschutz und Naturschutz und auch Denkmalschutz (Burg Reuschenberg, alte R\u00f6merstra\u00dfe, Sittarder Hof) v\u00f6llig egal.<\/p>","protected":false},"excerpt":{"rendered":"<p>Die Liberalen Demokraten NRW unterst\u00fctzen die Forderungen der am Tagebau Hambach sans\u00e4ssigen Landwirte, Grundbesitzer und Gemeinden keine Acker- und Landfl\u00e4chen zur Herstellung abgeflachter Uferb\u00f6schungen abzubaggern und zu zerst\u00f6ren. Auch die Fl\u00e4che des inzwischen fast v\u00f6llig zerst\u00f6rten Ortes Alt-Manheim kann f\u00fcr eine neue Ortsansiedlung genutzt werden, da alle Infratsrukturen bereits liegen. Hier k\u00f6nnte beispielsweise eine Niedrigenergiesiedlung [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2118,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[7],"tags":[12,13,14,15],"class_list":["post-1391","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kommentare","tag-hambach","tag-hambacher-forst","tag-tagebau","tag-uferboeschungen"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Uferb\u00f6schungen am Tagebau Hambach - Liberale Demokraten NRW<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ld-nrw.de\/en\/aktuelles\/uferboeschungen-am-tagebau-hambach\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uferb\u00f6schungen am Tagebau Hambach - Liberale Demokraten NRW\" \/>\n<meta property=\"og:description\" content=\"Die Liberalen Demokraten NRW unterst\u00fctzen die Forderungen der am Tagebau Hambach sans\u00e4ssigen Landwirte, Grundbesitzer und Gemeinden keine Acker- und Landfl\u00e4chen zur Herstellung abgeflachter Uferb\u00f6schungen abzubaggern und zu zerst\u00f6ren. Auch die Fl\u00e4che des inzwischen fast v\u00f6llig zerst\u00f6rten Ortes Alt-Manheim kann f\u00fcr eine neue Ortsansiedlung genutzt werden, da alle Infratsrukturen bereits liegen. Hier k\u00f6nnte beispielsweise eine Niedrigenergiesiedlung [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ld-nrw.de\/en\/aktuelles\/uferboeschungen-am-tagebau-hambach\/\" \/>\n<meta property=\"og:site_name\" content=\"Liberale Demokraten NRW\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ldnrw\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-02T16:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:05:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ld-nrw.de\/wp-content\/uploads\/2023\/07\/bucket-wheel-excavators-2454613_1920.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dr. Michael Kaiser\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ld_nrw\" \/>\n<meta name=\"twitter:site\" content=\"@ld_nrw\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dr. Michael Kaiser\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/uferboeschungen-am-tagebau-hambach\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/uferboeschungen-am-tagebau-hambach\\\/\"},\"author\":{\"name\":\"Dr. Michael Kaiser\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#\\\/schema\\\/person\\\/edbe23240e648a97142486dc35774b6a\"},\"headline\":\"Uferb\u00f6schungen am Tagebau Hambach\",\"datePublished\":\"2020-07-02T16:00:00+00:00\",\"dateModified\":\"2023-11-28T11:05:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/uferboeschungen-am-tagebau-hambach\\\/\"},\"wordCount\":337,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/uferboeschungen-am-tagebau-hambach\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ld-nrw.de\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/bucket-wheel-excavators-2454613_1920.jpg\",\"keywords\":[\"Hambach\",\"Hambacher Forst\",\"Tagebau\",\"Uferb\u00f6schungen\"],\"articleSection\":[\"Kommentar\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/uferboeschungen-am-tagebau-hambach\\\/\",\"url\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/uferboeschungen-am-tagebau-hambach\\\/\",\"name\":\"Uferb\u00f6schungen am Tagebau Hambach - Liberale Demokraten NRW\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/uferboeschungen-am-tagebau-hambach\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/uferboeschungen-am-tagebau-hambach\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ld-nrw.de\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/bucket-wheel-excavators-2454613_1920.jpg\",\"datePublished\":\"2020-07-02T16:00:00+00:00\",\"dateModified\":\"2023-11-28T11:05:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/uferboeschungen-am-tagebau-hambach\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/uferboeschungen-am-tagebau-hambach\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/uferboeschungen-am-tagebau-hambach\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ld-nrw.de\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/bucket-wheel-excavators-2454613_1920.jpg\",\"contentUrl\":\"https:\\\/\\\/ld-nrw.de\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/bucket-wheel-excavators-2454613_1920.jpg\",\"width\":1080,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/uferboeschungen-am-tagebau-hambach\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/ld-nrw.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uferb\u00f6schungen am Tagebau Hambach\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#website\",\"url\":\"https:\\\/\\\/ld-nrw.de\\\/\",\"name\":\"Liberale Demokraten NRW\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ld-nrw.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#organization\",\"name\":\"Liberale Demokraten NRW\",\"url\":\"https:\\\/\\\/ld-nrw.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ld-nrw.de\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/ld_nrw.svg\",\"contentUrl\":\"https:\\\/\\\/ld-nrw.de\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/ld_nrw.svg\",\"width\":1595,\"height\":776,\"caption\":\"Liberale Demokraten NRW\"},\"image\":{\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ldnrw\",\"https:\\\/\\\/x.com\\\/ld_nrw\",\"https:\\\/\\\/www.instagram.com\\\/ld_nrw\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#\\\/schema\\\/person\\\/edbe23240e648a97142486dc35774b6a\",\"name\":\"Dr. Michael Kaiser\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/c_001-801x1200-1-e1692971152732-96x96.webp\",\"url\":\"https:\\\/\\\/ld-nrw.de\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/c_001-801x1200-1-e1692971152732-96x96.webp\",\"contentUrl\":\"https:\\\/\\\/ld-nrw.de\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/c_001-801x1200-1-e1692971152732-96x96.webp\",\"caption\":\"Dr. Michael Kaiser\"},\"description\":\"Dr. Michael Kaiser war bis 2021 der Vorsitzende des Landesverbandes Nordrhein-Westfalen der Liberalen Demokraten.\",\"url\":\"https:\\\/\\\/ld-nrw.de\\\/en\\\/aktuelles\\\/author\\\/michaelkaiser\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Uferb\u00f6schungen am Tagebau Hambach - Liberale Demokraten NRW","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ld-nrw.de\/en\/aktuelles\/uferboeschungen-am-tagebau-hambach\/","og_locale":"en_GB","og_type":"article","og_title":"Uferb\u00f6schungen am Tagebau Hambach - Liberale Demokraten NRW","og_description":"Die Liberalen Demokraten NRW unterst\u00fctzen die Forderungen der am Tagebau Hambach sans\u00e4ssigen Landwirte, Grundbesitzer und Gemeinden keine Acker- und Landfl\u00e4chen zur Herstellung abgeflachter Uferb\u00f6schungen abzubaggern und zu zerst\u00f6ren. Auch die Fl\u00e4che des inzwischen fast v\u00f6llig zerst\u00f6rten Ortes Alt-Manheim kann f\u00fcr eine neue Ortsansiedlung genutzt werden, da alle Infratsrukturen bereits liegen. Hier k\u00f6nnte beispielsweise eine Niedrigenergiesiedlung [&hellip;]","og_url":"https:\/\/ld-nrw.de\/en\/aktuelles\/uferboeschungen-am-tagebau-hambach\/","og_site_name":"Liberale Demokraten NRW","article_publisher":"https:\/\/www.facebook.com\/ldnrw","article_published_time":"2020-07-02T16:00:00+00:00","article_modified_time":"2023-11-28T11:05:56+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/ld-nrw.de\/wp-content\/uploads\/2023\/07\/bucket-wheel-excavators-2454613_1920.jpg","type":"image\/jpeg"}],"author":"Dr. Michael Kaiser","twitter_card":"summary_large_image","twitter_creator":"@ld_nrw","twitter_site":"@ld_nrw","twitter_misc":{"Written by":"Dr. Michael Kaiser","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ld-nrw.de\/aktuelles\/uferboeschungen-am-tagebau-hambach\/#article","isPartOf":{"@id":"https:\/\/ld-nrw.de\/aktuelles\/uferboeschungen-am-tagebau-hambach\/"},"author":{"name":"Dr. Michael Kaiser","@id":"https:\/\/ld-nrw.de\/#\/schema\/person\/edbe23240e648a97142486dc35774b6a"},"headline":"Uferb\u00f6schungen am Tagebau Hambach","datePublished":"2020-07-02T16:00:00+00:00","dateModified":"2023-11-28T11:05:56+00:00","mainEntityOfPage":{"@id":"https:\/\/ld-nrw.de\/aktuelles\/uferboeschungen-am-tagebau-hambach\/"},"wordCount":337,"commentCount":0,"publisher":{"@id":"https:\/\/ld-nrw.de\/#organization"},"image":{"@id":"https:\/\/ld-nrw.de\/aktuelles\/uferboeschungen-am-tagebau-hambach\/#primaryimage"},"thumbnailUrl":"https:\/\/ld-nrw.de\/wp-content\/uploads\/2023\/07\/bucket-wheel-excavators-2454613_1920.jpg","keywords":["Hambach","Hambacher Forst","Tagebau","Uferb\u00f6schungen"],"articleSection":["Kommentar"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/ld-nrw.de\/aktuelles\/uferboeschungen-am-tagebau-hambach\/","url":"https:\/\/ld-nrw.de\/aktuelles\/uferboeschungen-am-tagebau-hambach\/","name":"Uferb\u00f6schungen am Tagebau Hambach - Liberale Demokraten NRW","isPartOf":{"@id":"https:\/\/ld-nrw.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ld-nrw.de\/aktuelles\/uferboeschungen-am-tagebau-hambach\/#primaryimage"},"image":{"@id":"https:\/\/ld-nrw.de\/aktuelles\/uferboeschungen-am-tagebau-hambach\/#primaryimage"},"thumbnailUrl":"https:\/\/ld-nrw.de\/wp-content\/uploads\/2023\/07\/bucket-wheel-excavators-2454613_1920.jpg","datePublished":"2020-07-02T16:00:00+00:00","dateModified":"2023-11-28T11:05:56+00:00","breadcrumb":{"@id":"https:\/\/ld-nrw.de\/aktuelles\/uferboeschungen-am-tagebau-hambach\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ld-nrw.de\/aktuelles\/uferboeschungen-am-tagebau-hambach\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/ld-nrw.de\/aktuelles\/uferboeschungen-am-tagebau-hambach\/#primaryimage","url":"https:\/\/ld-nrw.de\/wp-content\/uploads\/2023\/07\/bucket-wheel-excavators-2454613_1920.jpg","contentUrl":"https:\/\/ld-nrw.de\/wp-content\/uploads\/2023\/07\/bucket-wheel-excavators-2454613_1920.jpg","width":1080,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/ld-nrw.de\/aktuelles\/uferboeschungen-am-tagebau-hambach\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/ld-nrw.de\/"},{"@type":"ListItem","position":2,"name":"Uferb\u00f6schungen am Tagebau Hambach"}]},{"@type":"WebSite","@id":"https:\/\/ld-nrw.de\/#website","url":"https:\/\/ld-nrw.de\/","name":"Liberale Demokraten NRW","description":"","publisher":{"@id":"https:\/\/ld-nrw.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ld-nrw.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/ld-nrw.de\/#organization","name":"Liberale Demokraten NRW","url":"https:\/\/ld-nrw.de\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/ld-nrw.de\/#\/schema\/logo\/image\/","url":"https:\/\/ld-nrw.de\/wp-content\/uploads\/2023\/07\/ld_nrw.svg","contentUrl":"https:\/\/ld-nrw.de\/wp-content\/uploads\/2023\/07\/ld_nrw.svg","width":1595,"height":776,"caption":"Liberale Demokraten NRW"},"image":{"@id":"https:\/\/ld-nrw.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ldnrw","https:\/\/x.com\/ld_nrw","https:\/\/www.instagram.com\/ld_nrw\/"]},{"@type":"Person","@id":"https:\/\/ld-nrw.de\/#\/schema\/person\/edbe23240e648a97142486dc35774b6a","name":"Dr. Michael Kaiser","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/ld-nrw.de\/wp-content\/uploads\/2023\/08\/c_001-801x1200-1-e1692971152732-96x96.webp","url":"https:\/\/ld-nrw.de\/wp-content\/uploads\/2023\/08\/c_001-801x1200-1-e1692971152732-96x96.webp","contentUrl":"https:\/\/ld-nrw.de\/wp-content\/uploads\/2023\/08\/c_001-801x1200-1-e1692971152732-96x96.webp","caption":"Dr. Michael Kaiser"},"description":"Dr. Michael Kaiser war bis 2021 der Vorsitzende des Landesverbandes Nordrhein-Westfalen der Liberalen Demokraten.","url":"https:\/\/ld-nrw.de\/en\/aktuelles\/author\/michaelkaiser\/"}]}},"_links":{"self":[{"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/posts\/1391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/comments?post=1391"}],"version-history":[{"count":1,"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/posts\/1391\/revisions"}],"predecessor-version":[{"id":2353,"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/posts\/1391\/revisions\/2353"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/media\/2118"}],"wp:attachment":[{"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/media?parent=1391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/categories?post=1391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/tags?post=1391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}