{"id":2965,"date":"2021-08-29T12:25:00","date_gmt":"2021-08-29T10:25:00","guid":{"rendered":"https:\/\/ld-nrw.de\/?post_type=beschluss&#038;p=2965"},"modified":"2025-08-06T12:34:49","modified_gmt":"2025-08-06T10:34:49","slug":"polizeiarbeit","status":"publish","type":"beschluss","link":"https:\/\/ld-nrw.de\/en\/aktuelles\/beschluss\/polizeiarbeit\/","title":{"rendered":"Polizeiarbeit"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Die Verarbeitung von personenbezogenen Daten innerhalb von Ermittlungsbeh\u00f6rden ist strikter im Sinne des Datenschutzes zu regeln. Dabei ist die verdachtsunabh\u00e4ngige Erhebung von Daten, durch die eine Person identifizierbar ist, zu verbieten. Vielmehr sollen Ermittlungsbeh\u00f6rden auf klar begr\u00fcndetem Verdacht basierend Indien sowie Daten sammeln, sowie auf dieser Basis ihren Verdacht eingrenzen oder ausweiten k\u00f6nnen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dabei ist wichtig, dass diese Daten stets ermittlungsrelevant sowie themenbezogen bleiben. Die Speicherung und Verarbeitung von Daten unbeteiligter Personen ist strikt zu unterlassen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Vorhersagende Polizeiarbeit<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Bei dem sogenannten \u201ePredictive Policing\u201c, beziehungsweise vorhersagender Polizeiarbeit, handelt es sich darum, etwaige Verbrechen anhand statistischer Auswertungen vorherzusagen. Dabei werden bisherige Daten zu Verbrechern, Verbrechen, Standorten, Zeiten etc. in das System eingespeist. Das Ziel ist es, Verbrechen vorherzusagen, bevor diese passieren. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dabei mag es nahezu utopisch wirken, \u00fcber Verbrechen Bescheid zu wissen, bevor sie passieren. Letztlich w\u00e4re somit eine weitgehende Pr\u00e4vention m\u00f6glich. Allerdings werden hierbei die Schattenseiten der vorhersagenden Polizeiarbeit au\u00dfer Acht gelassen. Schlie\u00dflich werden hierbei nicht Muster in allen tats\u00e4chlich geschehenden Verbrechen beachtet \u2013 dies w\u00e4re aufgrund der Menge an Daten sowie vor allem an der Menge an unbekannten Verbrechen nicht m\u00f6glich \u2013 sondern vielmehr die bisherigen Ermittlungen der Polizei.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dabei werden Ortschaften, die die Polizei mehr frequentiert, st\u00e4rker dokumentiert sein als Ortschaften, in denen dies nicht der Fall ist. Das wird dazu f\u00fchren, dass diese Orte nicht deshalb st\u00e4rker gewichtet werden, weil dort tats\u00e4chlich mehr Verbrechen begangen werden, sondern weil die Polizei in der Vergangenheit an der Stelle mehr Pr\u00e4senz gezeigt und aufgrund ihrer Pr\u00e4senz mehr F\u00e4lle feststellen konnte. Aus dem Irrtum entspringend werden derartige Orte nun als Hotspots f\u00fcr Verbrechen markiert. So ist beispielsweise K\u00f6ln \u2013 Chorweiler in dem Artikel zur \u201eSKALA|MAP\u201c-Karte auf der Webseite des Landeskriminalamtes Nordrhein-Westfalen rot markiert. Dieser Umstand zeigt deutlich, dass die Bef\u00fcrchtungen in unserem Land bereits zur Realit\u00e4t werden. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es ist anzumerken, dass die Polizei in der Regel vor allem Gegenden, in denen mehr Personen mit geringerem Einkommen wohnen, st\u00e4rker kontrolliert. Somit ist es nicht nur realistisch, alle derartigen Gegenden systemseitig zum Hotspot f\u00fcr Verbrechen und Verbrecher zu ernennen, sondern Personen, die in diese Kategorien fallen, blo\u00df aufgrund dessen automatisiert negativ zu bewerten. Sofern in der Vergangenheit vorurteilhaft Verdacht gesch\u00f6pft wurde, werden<br>diese Vorurteile sich somit auch wiederholen, wenn nicht durch eben diese Wiederholungen umso st\u00e4rker ins Gewicht fallen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hinzu kommt, dass derartige Systeme oft sehr intransparent sind. So werden Daten in nicht quelloffenen Systemen verarbeitet. Selbst ihre m\u00f6glichen Schwachstellen werden in der Regel nicht mit der Menge an Transparenz gehandhabt, die f\u00fcr ein derartiges System erforderlich w\u00e4re. Auch fehlen f\u00fcr B\u00fcrger_innen leicht zug\u00e4ngliche Informationen \u00fcber die Fehlerquoten sowie \u00fcber die Konsequenzen f\u00fcr Personengruppen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir Liberale Demokraten notieren die Schwachstellen der vorhersagenden Polizeiarbeit und lehnen sie entschieden ab. Dazu ist das bereits im Einsatz befindliche Programm SKALA (System zur Kriminalit\u00e4tsauswertung und Lageantizipation) in Nordrhein-Westfalen umgehend einzustellen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Verdachts- und anlasslose Personenkontrollen<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die Praxis der verdachts- und anlasslosen Personenkontrollen lehnen wir ab. Sie ist inh\u00e4rent Vorurteilen und Stereotypen unterworfen. Etwaige Vorteile f\u00fcr die Fahndung wiegen die schwerwiegenden Folgen einer solchen als rassistisch wahrzunehmenden Benachteiligung im Alltag nicht auf.<\/p>","protected":false},"featured_media":0,"parent":0,"template":"","organ":[30],"class_list":["post-2965","beschluss","type-beschluss","status-publish","hentry","organ-landesparteitag"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Polizeiarbeit - Liberale Demokraten NRW<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ld-nrw.de\/en\/aktuelles\/beschluss\/polizeiarbeit\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Polizeiarbeit - Liberale Demokraten NRW\" \/>\n<meta property=\"og:description\" content=\"Die Verarbeitung von personenbezogenen Daten innerhalb von Ermittlungsbeh\u00f6rden ist strikter im Sinne des Datenschutzes zu regeln. Dabei ist die verdachtsunabh\u00e4ngige Erhebung von Daten, durch die eine Person identifizierbar ist, zu verbieten. Vielmehr sollen Ermittlungsbeh\u00f6rden auf klar begr\u00fcndetem Verdacht basierend Indien sowie Daten sammeln, sowie auf dieser Basis ihren Verdacht eingrenzen oder ausweiten k\u00f6nnen. Dabei ist [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ld-nrw.de\/en\/aktuelles\/beschluss\/polizeiarbeit\/\" \/>\n<meta property=\"og:site_name\" content=\"Liberale Demokraten NRW\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ldnrw\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-06T10:34:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ld_nrw\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/beschluss\\\/polizeiarbeit\\\/\",\"url\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/beschluss\\\/polizeiarbeit\\\/\",\"name\":\"Polizeiarbeit - Liberale Demokraten NRW\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#website\"},\"datePublished\":\"2021-08-29T10:25:00+00:00\",\"dateModified\":\"2025-08-06T10:34:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/beschluss\\\/polizeiarbeit\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/beschluss\\\/polizeiarbeit\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/beschluss\\\/polizeiarbeit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/ld-nrw.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Beschl\u00fcsse\",\"item\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/beschluesse\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Polizeiarbeit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#website\",\"url\":\"https:\\\/\\\/ld-nrw.de\\\/\",\"name\":\"Liberale Demokraten NRW\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ld-nrw.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#organization\",\"name\":\"Liberale Demokraten NRW\",\"url\":\"https:\\\/\\\/ld-nrw.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ld-nrw.de\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/ld_nrw.svg\",\"contentUrl\":\"https:\\\/\\\/ld-nrw.de\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/ld_nrw.svg\",\"width\":1595,\"height\":776,\"caption\":\"Liberale Demokraten NRW\"},\"image\":{\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ldnrw\",\"https:\\\/\\\/x.com\\\/ld_nrw\",\"https:\\\/\\\/www.instagram.com\\\/ld_nrw\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Polizeiarbeit - Liberale Demokraten NRW","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ld-nrw.de\/en\/aktuelles\/beschluss\/polizeiarbeit\/","og_locale":"en_GB","og_type":"article","og_title":"Polizeiarbeit - Liberale Demokraten NRW","og_description":"Die Verarbeitung von personenbezogenen Daten innerhalb von Ermittlungsbeh\u00f6rden ist strikter im Sinne des Datenschutzes zu regeln. Dabei ist die verdachtsunabh\u00e4ngige Erhebung von Daten, durch die eine Person identifizierbar ist, zu verbieten. Vielmehr sollen Ermittlungsbeh\u00f6rden auf klar begr\u00fcndetem Verdacht basierend Indien sowie Daten sammeln, sowie auf dieser Basis ihren Verdacht eingrenzen oder ausweiten k\u00f6nnen. Dabei ist [&hellip;]","og_url":"https:\/\/ld-nrw.de\/en\/aktuelles\/beschluss\/polizeiarbeit\/","og_site_name":"Liberale Demokraten NRW","article_publisher":"https:\/\/www.facebook.com\/ldnrw","article_modified_time":"2025-08-06T10:34:49+00:00","twitter_card":"summary_large_image","twitter_site":"@ld_nrw","twitter_misc":{"Estimated reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ld-nrw.de\/aktuelles\/beschluss\/polizeiarbeit\/","url":"https:\/\/ld-nrw.de\/aktuelles\/beschluss\/polizeiarbeit\/","name":"Polizeiarbeit - Liberale Demokraten NRW","isPartOf":{"@id":"https:\/\/ld-nrw.de\/#website"},"datePublished":"2021-08-29T10:25:00+00:00","dateModified":"2025-08-06T10:34:49+00:00","breadcrumb":{"@id":"https:\/\/ld-nrw.de\/aktuelles\/beschluss\/polizeiarbeit\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ld-nrw.de\/aktuelles\/beschluss\/polizeiarbeit\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ld-nrw.de\/aktuelles\/beschluss\/polizeiarbeit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/ld-nrw.de\/"},{"@type":"ListItem","position":2,"name":"Beschl\u00fcsse","item":"https:\/\/ld-nrw.de\/aktuelles\/beschluesse\/"},{"@type":"ListItem","position":3,"name":"Polizeiarbeit"}]},{"@type":"WebSite","@id":"https:\/\/ld-nrw.de\/#website","url":"https:\/\/ld-nrw.de\/","name":"Liberale Demokraten NRW","description":"","publisher":{"@id":"https:\/\/ld-nrw.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ld-nrw.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/ld-nrw.de\/#organization","name":"Liberale Demokraten NRW","url":"https:\/\/ld-nrw.de\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/ld-nrw.de\/#\/schema\/logo\/image\/","url":"https:\/\/ld-nrw.de\/wp-content\/uploads\/2023\/07\/ld_nrw.svg","contentUrl":"https:\/\/ld-nrw.de\/wp-content\/uploads\/2023\/07\/ld_nrw.svg","width":1595,"height":776,"caption":"Liberale Demokraten NRW"},"image":{"@id":"https:\/\/ld-nrw.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ldnrw","https:\/\/x.com\/ld_nrw","https:\/\/www.instagram.com\/ld_nrw\/"]}]}},"_links":{"self":[{"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/beschluss\/2965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/beschluss"}],"about":[{"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/types\/beschluss"}],"wp:attachment":[{"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/media?parent=2965"}],"wp:term":[{"taxonomy":"organ","embeddable":true,"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/organ?post=2965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}