{"id":2802,"date":"2021-08-29T08:24:00","date_gmt":"2021-08-29T06:24:00","guid":{"rendered":"https:\/\/ld-nrw.de\/?post_type=beschluss&#038;p=2802"},"modified":"2024-10-18T08:32:49","modified_gmt":"2024-10-18T06:32:49","slug":"ausbildungsfoerderung","status":"publish","type":"beschluss","link":"https:\/\/ld-nrw.de\/en\/aktuelles\/beschluss\/ausbildungsfoerderung\/","title":{"rendered":"Ausbildungsf\u00f6rderung"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Die Ausbildungsf\u00f6rderung ist bislang im Rahmen des Bundesausbildungsf\u00f6rderungsgesetzes (BAf\u00f6G) insbesondere eine Bundessache. Allerdings sehen wir ein, dass das BAf\u00f6G in seiner derzeitigen Form nicht sozialvertr\u00e4glich ist. Daher fordern wir eine erg\u00e4nzende Landesausbildungsf\u00f6rderung, bis die L\u00fccken im BAf\u00f6G geschlossen werden oder dieses durch ein sozialvertr\u00e4gliches faires Grundeinkommen \u00fcberfl\u00fcssig wird.<br><br>Hierbei sollen Personen von dieser Landesausbildungsf\u00f6rderung Gebrauch machen k\u00f6nnen, die keine Berechtigung zur F\u00f6rderung nach BAf\u00f6G besitzen haben und deren BAf\u00f6G-Antrag abgelehnt wurde. Zur Vereinfachung des Antragsverfahrens sollen hierbei maximal dieselben Daten wie f\u00fcr den BAf\u00f6G-Antrag erforderlich sein und unter Zustimmung des Antragstellers vielmehr auch die Daten vom vorangegangenen BAf\u00f6G-Antrag \u00fcbernommen werden k\u00f6nnen. Damit wird ein erneutes Ausf\u00fcllen von Formbl\u00e4ttern nicht n\u00f6tig und die Person kann sich voll und ganz auf ihre Ausbildung oder ihr Studium konzentrieren.<br><br>Gef\u00f6rdert werden die Antragsteller hierbei gemessen an ihrer individuellen finanziellen Situation und somit unabh\u00e4ngig von den Eltern. Dabei wird ein Leistungsnachweis nicht so strikt bewertet wie beim BAf\u00f6G. Vielmehr sollen die individuellen Umst\u00e4nde der Person, sowie ob sie mit ihrer Ausbildung oder ihrem Studium weiterkommt, bewertet werden. Eine \u00fcber die Regelstudienzeit hinaus dauernde Studienzeit soll hierbei nicht negativ auf die F\u00f6rderung auswirken, solange diese nicht um die H\u00e4lfte der Regelzeit l\u00e4nger andauert. Zus\u00e4tzlich sind etwaige Bet\u00e4tigungen in den Hochschul- und studentischen beziehungsweise in betrieblichen oder gewerkschaftlichen Gremien zu ber\u00fccksichtigen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mit dieser Landesausbildungsf\u00f6rderung wird bezweckt, Studierende sowie Auszubildende individuell zu bewerten, sowie sie nicht unter Leistungsdruck zu setzen. Denn eine an der erbrachten Leistung gemessene F\u00f6rderung w\u00fcrde eher einer Begabtenf\u00f6rderung als einer staatlichen St\u00fctze entsprechen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"featured_media":0,"parent":0,"template":"","organ":[30],"class_list":["post-2802","beschluss","type-beschluss","status-publish","hentry","organ-landesparteitag"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ausbildungsf\u00f6rderung - Liberale Demokraten NRW<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ld-nrw.de\/en\/aktuelles\/beschluss\/ausbildungsfoerderung\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ausbildungsf\u00f6rderung - Liberale Demokraten NRW\" \/>\n<meta property=\"og:description\" content=\"Die Ausbildungsf\u00f6rderung ist bislang im Rahmen des Bundesausbildungsf\u00f6rderungsgesetzes (BAf\u00f6G) insbesondere eine Bundessache. Allerdings sehen wir ein, dass das BAf\u00f6G in seiner derzeitigen Form nicht sozialvertr\u00e4glich ist. Daher fordern wir eine erg\u00e4nzende Landesausbildungsf\u00f6rderung, bis die L\u00fccken im BAf\u00f6G geschlossen werden oder dieses durch ein sozialvertr\u00e4gliches faires Grundeinkommen \u00fcberfl\u00fcssig wird. Hierbei sollen Personen von dieser Landesausbildungsf\u00f6rderung Gebrauch [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ld-nrw.de\/en\/aktuelles\/beschluss\/ausbildungsfoerderung\/\" \/>\n<meta property=\"og:site_name\" content=\"Liberale Demokraten NRW\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ldnrw\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-18T06:32:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ld_nrw\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/beschluss\\\/ausbildungsfoerderung\\\/\",\"url\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/beschluss\\\/ausbildungsfoerderung\\\/\",\"name\":\"Ausbildungsf\u00f6rderung - Liberale Demokraten NRW\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#website\"},\"datePublished\":\"2021-08-29T06:24:00+00:00\",\"dateModified\":\"2024-10-18T06:32:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/beschluss\\\/ausbildungsfoerderung\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/beschluss\\\/ausbildungsfoerderung\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/beschluss\\\/ausbildungsfoerderung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/ld-nrw.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Beschl\u00fcsse\",\"item\":\"https:\\\/\\\/ld-nrw.de\\\/aktuelles\\\/beschluesse\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ausbildungsf\u00f6rderung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#website\",\"url\":\"https:\\\/\\\/ld-nrw.de\\\/\",\"name\":\"Liberale Demokraten NRW\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ld-nrw.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#organization\",\"name\":\"Liberale Demokraten NRW\",\"url\":\"https:\\\/\\\/ld-nrw.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ld-nrw.de\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/ld_nrw.svg\",\"contentUrl\":\"https:\\\/\\\/ld-nrw.de\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/ld_nrw.svg\",\"width\":1595,\"height\":776,\"caption\":\"Liberale Demokraten NRW\"},\"image\":{\"@id\":\"https:\\\/\\\/ld-nrw.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ldnrw\",\"https:\\\/\\\/x.com\\\/ld_nrw\",\"https:\\\/\\\/www.instagram.com\\\/ld_nrw\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ausbildungsf\u00f6rderung - Liberale Demokraten NRW","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ld-nrw.de\/en\/aktuelles\/beschluss\/ausbildungsfoerderung\/","og_locale":"en_GB","og_type":"article","og_title":"Ausbildungsf\u00f6rderung - Liberale Demokraten NRW","og_description":"Die Ausbildungsf\u00f6rderung ist bislang im Rahmen des Bundesausbildungsf\u00f6rderungsgesetzes (BAf\u00f6G) insbesondere eine Bundessache. Allerdings sehen wir ein, dass das BAf\u00f6G in seiner derzeitigen Form nicht sozialvertr\u00e4glich ist. Daher fordern wir eine erg\u00e4nzende Landesausbildungsf\u00f6rderung, bis die L\u00fccken im BAf\u00f6G geschlossen werden oder dieses durch ein sozialvertr\u00e4gliches faires Grundeinkommen \u00fcberfl\u00fcssig wird. Hierbei sollen Personen von dieser Landesausbildungsf\u00f6rderung Gebrauch [&hellip;]","og_url":"https:\/\/ld-nrw.de\/en\/aktuelles\/beschluss\/ausbildungsfoerderung\/","og_site_name":"Liberale Demokraten NRW","article_publisher":"https:\/\/www.facebook.com\/ldnrw","article_modified_time":"2024-10-18T06:32:49+00:00","twitter_card":"summary_large_image","twitter_site":"@ld_nrw","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ld-nrw.de\/aktuelles\/beschluss\/ausbildungsfoerderung\/","url":"https:\/\/ld-nrw.de\/aktuelles\/beschluss\/ausbildungsfoerderung\/","name":"Ausbildungsf\u00f6rderung - Liberale Demokraten NRW","isPartOf":{"@id":"https:\/\/ld-nrw.de\/#website"},"datePublished":"2021-08-29T06:24:00+00:00","dateModified":"2024-10-18T06:32:49+00:00","breadcrumb":{"@id":"https:\/\/ld-nrw.de\/aktuelles\/beschluss\/ausbildungsfoerderung\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ld-nrw.de\/aktuelles\/beschluss\/ausbildungsfoerderung\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ld-nrw.de\/aktuelles\/beschluss\/ausbildungsfoerderung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/ld-nrw.de\/"},{"@type":"ListItem","position":2,"name":"Beschl\u00fcsse","item":"https:\/\/ld-nrw.de\/aktuelles\/beschluesse\/"},{"@type":"ListItem","position":3,"name":"Ausbildungsf\u00f6rderung"}]},{"@type":"WebSite","@id":"https:\/\/ld-nrw.de\/#website","url":"https:\/\/ld-nrw.de\/","name":"Liberale Demokraten NRW","description":"","publisher":{"@id":"https:\/\/ld-nrw.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ld-nrw.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/ld-nrw.de\/#organization","name":"Liberale Demokraten NRW","url":"https:\/\/ld-nrw.de\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/ld-nrw.de\/#\/schema\/logo\/image\/","url":"https:\/\/ld-nrw.de\/wp-content\/uploads\/2023\/07\/ld_nrw.svg","contentUrl":"https:\/\/ld-nrw.de\/wp-content\/uploads\/2023\/07\/ld_nrw.svg","width":1595,"height":776,"caption":"Liberale Demokraten NRW"},"image":{"@id":"https:\/\/ld-nrw.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ldnrw","https:\/\/x.com\/ld_nrw","https:\/\/www.instagram.com\/ld_nrw\/"]}]}},"_links":{"self":[{"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/beschluss\/2802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/beschluss"}],"about":[{"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/types\/beschluss"}],"wp:attachment":[{"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/media?parent=2802"}],"wp:term":[{"taxonomy":"organ","embeddable":true,"href":"https:\/\/ld-nrw.de\/en\/wp-json\/wp\/v2\/organ?post=2802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}